﻿{"id":1375,"date":"2019-11-04T12:06:59","date_gmt":"2019-11-04T12:06:59","guid":{"rendered":"https:\/\/sv-gebelzig.de\/?p=1375"},"modified":"2019-11-04T12:07:07","modified_gmt":"2019-11-04T12:07:07","slug":"fv-rot-weiss-93-olbersdorf-vs-sv-gebelzig-32","status":"publish","type":"post","link":"https:\/\/sv-gebelzig.de\/index.php\/2019\/11\/04\/fv-rot-weiss-93-olbersdorf-vs-sv-gebelzig-32\/","title":{"rendered":"FV Rot-Wei\u00df 93 Olbersdorf vs. SV Gebelzig (3:2)"},"content":{"rendered":"\n<p>Der SV Gebelzig vers\u00e4umte es, beim Ausw\u00e4rtsspiel in Olbersdorf wichtige Punkte gegen den Abstieg zu sammeln. Stattdessen rutschte man erstmals in dieser Saison auf den letzten Tabellenplatz ab.<\/p>\n\n\n\n<p>Diese Niederlage gegen schwache Gastgeber war v\u00f6llig unn\u00f6tig. Bereits nach 9 Minuten setzte Torj\u00e4ger K.Robert einen Fernschuss auf die Querlatte, doch die Tore erzielte der FV Olbersdorf. Beg\u00fcnstigt durch Abwehrfehler konnte sich M.Rudolf die Ecke zur F\u00fchrung aussuchen (11.). Nur 5 Minuten sp\u00e4ter schob St.Saalbach das Leder aus knapp 20 Meter Entfernung erneut ins verwaiste Gebelziger Tor (16.). Und auch R.Wunderlich trug sich mit einem trockenen Schuss aus etwa 20 Metern in die Torsch\u00fctzenliste ein (32.). Der Anschlusstreffer blieb den G\u00e4sten vor der Pause verwehrt, da sowohl K.Robert als auch H.Trocha ihre Chancen nicht nutzen konnten.<\/p>\n\n\n\n<p>Die zweite Halbzeit begann f\u00fcr den SVG mit einem Traumstart. R.L\u00e4tsch bediente H.Trocha auf der rechten Seite, der sich den Ball im Strafraum sogar noch zurechtlegen konnte und flach ins lange Eck vollendete (47.). Und auch K.Robert \u00fcberwand nach einem Zuspiel des eingewechselten N.Richter den Olbersdorfer Torwart R.Jungmichel zum Anschlusstreffer (52.). Hoffnung auf zumindest einen Ausw\u00e4rtspunkt keimte auf, zumal noch \u00fcber eine halbe Stunde zu spielen war. Jedoch endete die Druckphase der Gebelziger nach 65 Minuten und die Olbersdorfer fanden ins Spiel zur\u00fcck. Am Ende nahmen sie geschickt immer wieder Zeit von der Uhr und retteten den knappen Vorsprung zum ersten Saisonsieg bis zum Schlusspfiff.<\/p>\n\n\n\n<p>Es zeigte sich einmal mehr, dass in dieser Liga eine ordentliche Halbzeit nicht zum Punktgewinn ausreicht und individuelle Fehler knallhart bestraft werden. Die Gebelziger sollten im n\u00e4chsten Heimspiel gegen Kemnitz an die starke zweite Halbzeit ankn\u00fcpfen, um weitere Punkte einzufahren.<\/p>\n\n\n\n<p>\u00a9 Torsten Kalich<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der SV Gebelzig vers\u00e4umte es, beim Ausw\u00e4rtsspiel in Olbersdorf wichtige Punkte gegen den Abstieg zu sammeln. Stattdessen rutschte man erstmals in dieser Saison auf den letzten Tabellenplatz ab. Diese Niederlage gegen schwache Gastgeber war&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":237,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"_links":{"self":[{"href":"https:\/\/sv-gebelzig.de\/index.php\/wp-json\/wp\/v2\/posts\/1375"}],"collection":[{"href":"https:\/\/sv-gebelzig.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sv-gebelzig.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sv-gebelzig.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sv-gebelzig.de\/index.php\/wp-json\/wp\/v2\/comments?post=1375"}],"version-history":[{"count":2,"href":"https:\/\/sv-gebelzig.de\/index.php\/wp-json\/wp\/v2\/posts\/1375\/revisions"}],"predecessor-version":[{"id":1377,"href":"https:\/\/sv-gebelzig.de\/index.php\/wp-json\/wp\/v2\/posts\/1375\/revisions\/1377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sv-gebelzig.de\/index.php\/wp-json\/wp\/v2\/media\/237"}],"wp:attachment":[{"href":"https:\/\/sv-gebelzig.de\/index.php\/wp-json\/wp\/v2\/media?parent=1375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sv-gebelzig.de\/index.php\/wp-json\/wp\/v2\/categories?post=1375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sv-gebelzig.de\/index.php\/wp-json\/wp\/v2\/tags?post=1375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}